{"id":63928,"date":"2022-08-01T14:35:20","date_gmt":"2022-08-01T12:35:20","guid":{"rendered":"https:\/\/www.luciferos.us\/?page_id=63928"},"modified":"2025-07-01T09:36:45","modified_gmt":"2025-07-01T07:36:45","slug":"azienda","status":"publish","type":"page","link":"https:\/\/www.luciferos.us\/it\/azienda\/","title":{"rendered":"Chi siamo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_row_inner row_type=&#8221;row&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221;][vc_column_inner][vc_column_text]<\/p>\n<h1><span style=\"color: #000000;\"><strong>Chi siamo<\/strong><\/span><\/h1>\n<p><span style=\"color: #000000;\"><strong><br \/>\n<\/strong><\/span><span style=\"color: #919191;\">DAL 1978 DIAMO SPAZIO ALLA LUCE\u00a0<\/span>[\/vc_column_text][vc_empty_space][vc_single_image image=&#8221;114011&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space][vc_column_text]<\/p>\n<h1><strong><span style=\"color: #000000;\">Dal 1978 diamo spazio alla luce. Realizziamo idee illuminate, coniugando creativit\u00e0, innovazione e curiosit\u00e0. Progettiamo nuove soluzioni, attraverso lo studio e la ricerca, per creare sempre una luce migliore.<\/span><\/strong><\/h1>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;64px&#8221;][vc_column_text]La nostra forza non si specifica solo attraverso i nostri prodotti ma vede la sua massima espressione in un approccio trasversale. Alla complessit\u00e0 delle necessit\u00e0 dei nostri clienti, rispondiamo con un dialogo continuo e con la condivisione di risposte tailor made. Con una grande forza distributiva. Con un valore unico che racchiude la nostra filosofia: il Made in Italy. E ultimo, ma non di certo ultimo, il nostro pi\u00f9 grande vanto. Un team di progettisti in grado di descrivere la luce attraverso ombre, contrasti e contrappunti ritmici per guidarvi con attenzione, intuizione e capacit\u00e0 tecnologica nel mondo del lighting design.[\/vc_column_text][vc_empty_space height=&#8221;64px&#8221;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;63955,63957,63974,63976,63980,63978,63964,63970&#8243; img_size=&#8221;medium&#8221; column_number=&#8221;4&#8243; grayscale=&#8221;no&#8221; images_space=&#8221;gallery_with_space&#8221;][vc_empty_space height=&#8221;64px&#8221;][vc_separator type=&#8221;normal&#8221; color=&#8221;#a3a3a3&#8243;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8221;64px&#8221;][vc_single_image image=&#8221;114031&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;64px&#8221;][vc_single_image image=&#8221;114025&#8243; img_size=&#8221;large&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space height=&#8221;64px&#8221;][vc_column_text]<\/p>\n<pre><strong>MISSION<\/strong><\/pre>\n<h3><strong><span style=\"color: #000000;\">Progettiamo dettagli<\/span><br \/>\n<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Il nostro obiettivo \u00e8 integrare con armonia il corpo illuminante con l\u2019architettura, in continuit\u00e0 con le funzioni dello spazio che lo accoglie. Per questo motivo definiamo Lucifero\u2019s con l\u2019accezione di Archi-Tech Lighting. Un\u2019espressione che accoglie l\u2019alto standing di progettualit\u00e0, in grado di esaudire le necessit\u00e0 di qualsivoglia applicazione. Che sia retail, hospitality, museale, educational o green.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;64px&#8221;][vc_single_image image=&#8221;114027&#8243; img_size=&#8221;large&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space height=&#8221;64px&#8221;][vc_column_text]<\/p>\n<pre><strong>VISION<\/strong><\/pre>\n<h3><strong>Luce sul futuro<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>La tecnologia si muove velocemente. E noi con essa. L\u2019illuminazione gioca un ruolo cruciale nel design, in quanto porta l\u2019attenzione sulla sostenibilit\u00e0. Parliamo di risparmio energetico, di vivibilit\u00e0. Di integrazione di processi utili per ricalibrare il rapporto dell\u2019uomo con la natura.[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_empty_space height=&#8221;64px&#8221;]<a itemprop=\"url\" href=\"https:\/\/www.luciferos.us\/wp-content\/uploads\/2023\/10\/COMPANY-PROFILE-Ita-Eng.pdf\" target=\"_blank\" class=\"qbutton  default cta-button btn-center\" style=\"background-color:#919191;\" rel=\"noopener\">Profilo Azienda<\/a>[vc_empty_space height=&#8221;64px&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_row_inner row_type=&#8221;row&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; css_animation=&#8221;&#8221;][vc_column_inner][vc_column_text] Chi siamo DAL 1978 DIAMO SPAZIO ALLA LUCE\u00a0[\/vc_column_text][vc_empty_space][vc_single_image image=&#8221;114011&#8243; img_size=&#8221;full&#8221; qode_css_animation=&#8221;&#8221;][vc_empty_space][vc_column_text] Dal 1978 diamo spazio alla luce. Realizziamo idee illuminate, coniugando creativit\u00e0, innovazione e curiosit\u00e0. Progettiamo nuove soluzioni, attraverso lo studio e la&#8230;<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-63928","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.luciferos.us\/it\/wp-json\/wp\/v2\/pages\/63928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.luciferos.us\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.luciferos.us\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.luciferos.us\/it\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.luciferos.us\/it\/wp-json\/wp\/v2\/comments?post=63928"}],"version-history":[{"count":10,"href":"https:\/\/www.luciferos.us\/it\/wp-json\/wp\/v2\/pages\/63928\/revisions"}],"predecessor-version":[{"id":114035,"href":"https:\/\/www.luciferos.us\/it\/wp-json\/wp\/v2\/pages\/63928\/revisions\/114035"}],"wp:attachment":[{"href":"https:\/\/www.luciferos.us\/it\/wp-json\/wp\/v2\/media?parent=63928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}